{"id":577,"date":"2011-02-01T17:57:04","date_gmt":"2011-02-01T16:57:04","guid":{"rendered":"http:\/\/facseguridad.wordpress.com\/2011\/02\/01\/antirrobo-car-2002\/"},"modified":"2011-02-01T17:57:04","modified_gmt":"2011-02-01T16:57:04","slug":"antirrobo-car-2002","status":"publish","type":"post","link":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/","title":{"rendered":"Antirrobo Car 2002"},"content":{"rendered":"<div style=\"text-align:left;padding:3px\">\n<a href=\"http:\/\/www.flickr.com\/photos\/59004579@N05\/5407504357\/\" title=\"photo sharing\"><img decoding=\"async\" src=\"http:\/\/farm6.static.flickr.com\/5051\/5407504357_e7f1f2810e.jpg\" style=\"border:solid 2px #000000\" alt=\"\" \/><\/a><br \/>\n<br \/>\n<span style=\"font-size:.8em;margin-top:0\"><a href=\"http:\/\/www.flickr.com\/photos\/59004579@N05\/5407504357\/\">Antirrobo Car 2002<\/a>, originalmente cargada por <a href=\"http:\/\/www.flickr.com\/people\/59004579@N05\/\">fac seguridad<\/a>.<\/span>\n<\/div>\n<p>\nCuerpo acabado pintado y cromado.<br \/>\nCon arco de Acero calibrado de 10 y 12 mm. aseguramos m\u00e1xima resistencia.<br \/>\nCilindro de lat\u00f3n con dos llaves de 6 claves.<br \/>\nFac trabaja por la seguridad, somos expertos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antirrobo Car 2002, originalmente cargada por fac seguridad. Cuerpo acabado pintado y cromado. Con arco de Acero calibrado de 10 y 12 mm. aseguramos m\u00e1xima resistencia. Cilindro de lat\u00f3n con dos llaves de 6 claves. Fac trabaja por la seguridad, somos expertos.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[4],"tags":[187,305,320],"class_list":["post-577","post","type-post","status-publish","format-standard","hentry","category-general","tag-fiabilidad","tag-resistencia","tag-seguridad","post_format-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Antirrobo Car 2002 - Blog de FAC Seguridad<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antirrobo Car 2002 - Blog de FAC Seguridad\" \/>\n<meta property=\"og:description\" content=\"Antirrobo Car 2002, originalmente cargada por fac seguridad. Cuerpo acabado pintado y cromado. Con arco de Acero calibrado de 10 y 12 mm. aseguramos m\u00e1xima resistencia. Cilindro de lat\u00f3n con dos llaves de 6 claves. Fac trabaja por la seguridad, somos expertos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de FAC Seguridad\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fac.seguridad\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-01T16:57:04+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/farm6.static.flickr.com\/5051\/5407504357_e7f1f2810e.jpg\" \/>\n<meta name=\"author\" content=\"CommunityManagerFAC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fac_seguridad\" \/>\n<meta name=\"twitter:site\" content=\"@fac_seguridad\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"CommunityManagerFAC\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/\"},\"author\":{\"name\":\"CommunityManagerFAC\",\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/#\/schema\/person\/1f07a60c4f2a7462b44f0f1f41f49ef7\"},\"headline\":\"Antirrobo Car 2002\",\"datePublished\":\"2011-02-01T16:57:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/\"},\"wordCount\":42,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/#organization\"},\"image\":{\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/farm6.static.flickr.com\/5051\/5407504357_e7f1f2810e.jpg\",\"keywords\":[\"fiabilidad\",\"resistencia\",\"seguridad\"],\"articleSection\":[\"General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/\",\"url\":\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/\",\"name\":\"Antirrobo Car 2002 - Blog de FAC Seguridad\",\"isPartOf\":{\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/farm6.static.flickr.com\/5051\/5407504357_e7f1f2810e.jpg\",\"datePublished\":\"2011-02-01T16:57:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#primaryimage\",\"url\":\"http:\/\/farm6.static.flickr.com\/5051\/5407504357_e7f1f2810e.jpg\",\"contentUrl\":\"http:\/\/farm6.static.flickr.com\/5051\/5407504357_e7f1f2810e.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/fac-seguridad.es\/blogfac\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antirrobo Car 2002\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/#website\",\"url\":\"https:\/\/fac-seguridad.es\/blogfac\/\",\"name\":\"Blog de FAC Seguridad\",\"description\":\"Todas las novedades de FAC Seguridad\",\"publisher\":{\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fac-seguridad.es\/blogfac\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/#organization\",\"name\":\"FAC Seguridad\",\"url\":\"https:\/\/fac-seguridad.es\/blogfac\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fac-seguridad.es\/blogfac\/wp-content\/uploads\/sites\/2\/2020\/11\/FAC-cuadrado-scaled.jpg\",\"contentUrl\":\"https:\/\/fac-seguridad.es\/blogfac\/wp-content\/uploads\/sites\/2\/2020\/11\/FAC-cuadrado-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"FAC Seguridad\"},\"image\":{\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/fac.seguridad\/\",\"https:\/\/x.com\/fac_seguridad\",\"https:\/\/www.instagram.com\/fac_seguridad\/\",\"https:\/\/www.linkedin.com\/company\/fac-seguridad-s.a.\/\",\"https:\/\/www.youtube.com\/facseguridad\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/#\/schema\/person\/1f07a60c4f2a7462b44f0f1f41f49ef7\",\"name\":\"CommunityManagerFAC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fac-seguridad.es\/blogfac\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1a7c250877ed3dd65166e32ec4ceb6dd218c361ebe3f693b94d06b65745d76d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1a7c250877ed3dd65166e32ec4ceb6dd218c361ebe3f693b94d06b65745d76d6?s=96&d=mm&r=g\",\"caption\":\"CommunityManagerFAC\"},\"sameAs\":[\"http:\/\/fac-seguridad.es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antirrobo Car 2002 - Blog de FAC Seguridad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/","og_locale":"es_ES","og_type":"article","og_title":"Antirrobo Car 2002 - Blog de FAC Seguridad","og_description":"Antirrobo Car 2002, originalmente cargada por fac seguridad. Cuerpo acabado pintado y cromado. Con arco de Acero calibrado de 10 y 12 mm. aseguramos m\u00e1xima resistencia. Cilindro de lat\u00f3n con dos llaves de 6 claves. Fac trabaja por la seguridad, somos expertos.","og_url":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/","og_site_name":"Blog de FAC Seguridad","article_publisher":"https:\/\/www.facebook.com\/fac.seguridad\/","article_published_time":"2011-02-01T16:57:04+00:00","og_image":[{"url":"http:\/\/farm6.static.flickr.com\/5051\/5407504357_e7f1f2810e.jpg","type":"","width":"","height":""}],"author":"CommunityManagerFAC","twitter_card":"summary_large_image","twitter_creator":"@fac_seguridad","twitter_site":"@fac_seguridad","twitter_misc":{"Escrito por":"CommunityManagerFAC"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#article","isPartOf":{"@id":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/"},"author":{"name":"CommunityManagerFAC","@id":"https:\/\/fac-seguridad.es\/blogfac\/#\/schema\/person\/1f07a60c4f2a7462b44f0f1f41f49ef7"},"headline":"Antirrobo Car 2002","datePublished":"2011-02-01T16:57:04+00:00","mainEntityOfPage":{"@id":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/"},"wordCount":42,"commentCount":0,"publisher":{"@id":"https:\/\/fac-seguridad.es\/blogfac\/#organization"},"image":{"@id":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#primaryimage"},"thumbnailUrl":"http:\/\/farm6.static.flickr.com\/5051\/5407504357_e7f1f2810e.jpg","keywords":["fiabilidad","resistencia","seguridad"],"articleSection":["General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/","url":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/","name":"Antirrobo Car 2002 - Blog de FAC Seguridad","isPartOf":{"@id":"https:\/\/fac-seguridad.es\/blogfac\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#primaryimage"},"image":{"@id":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#primaryimage"},"thumbnailUrl":"http:\/\/farm6.static.flickr.com\/5051\/5407504357_e7f1f2810e.jpg","datePublished":"2011-02-01T16:57:04+00:00","breadcrumb":{"@id":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#primaryimage","url":"http:\/\/farm6.static.flickr.com\/5051\/5407504357_e7f1f2810e.jpg","contentUrl":"http:\/\/farm6.static.flickr.com\/5051\/5407504357_e7f1f2810e.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/fac-seguridad.es\/blogfac\/antirrobo-car-2002\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fac-seguridad.es\/blogfac\/"},{"@type":"ListItem","position":2,"name":"Antirrobo Car 2002"}]},{"@type":"WebSite","@id":"https:\/\/fac-seguridad.es\/blogfac\/#website","url":"https:\/\/fac-seguridad.es\/blogfac\/","name":"Blog de FAC Seguridad","description":"Todas las novedades de FAC Seguridad","publisher":{"@id":"https:\/\/fac-seguridad.es\/blogfac\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fac-seguridad.es\/blogfac\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fac-seguridad.es\/blogfac\/#organization","name":"FAC Seguridad","url":"https:\/\/fac-seguridad.es\/blogfac\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fac-seguridad.es\/blogfac\/#\/schema\/logo\/image\/","url":"https:\/\/fac-seguridad.es\/blogfac\/wp-content\/uploads\/sites\/2\/2020\/11\/FAC-cuadrado-scaled.jpg","contentUrl":"https:\/\/fac-seguridad.es\/blogfac\/wp-content\/uploads\/sites\/2\/2020\/11\/FAC-cuadrado-scaled.jpg","width":2560,"height":2560,"caption":"FAC Seguridad"},"image":{"@id":"https:\/\/fac-seguridad.es\/blogfac\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fac.seguridad\/","https:\/\/x.com\/fac_seguridad","https:\/\/www.instagram.com\/fac_seguridad\/","https:\/\/www.linkedin.com\/company\/fac-seguridad-s.a.\/","https:\/\/www.youtube.com\/facseguridad\/"]},{"@type":"Person","@id":"https:\/\/fac-seguridad.es\/blogfac\/#\/schema\/person\/1f07a60c4f2a7462b44f0f1f41f49ef7","name":"CommunityManagerFAC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fac-seguridad.es\/blogfac\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1a7c250877ed3dd65166e32ec4ceb6dd218c361ebe3f693b94d06b65745d76d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1a7c250877ed3dd65166e32ec4ceb6dd218c361ebe3f693b94d06b65745d76d6?s=96&d=mm&r=g","caption":"CommunityManagerFAC"},"sameAs":["http:\/\/fac-seguridad.es"]}]}},"_links":{"self":[{"href":"https:\/\/fac-seguridad.es\/blogfac\/wp-json\/wp\/v2\/posts\/577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fac-seguridad.es\/blogfac\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fac-seguridad.es\/blogfac\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fac-seguridad.es\/blogfac\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fac-seguridad.es\/blogfac\/wp-json\/wp\/v2\/comments?post=577"}],"version-history":[{"count":0,"href":"https:\/\/fac-seguridad.es\/blogfac\/wp-json\/wp\/v2\/posts\/577\/revisions"}],"wp:attachment":[{"href":"https:\/\/fac-seguridad.es\/blogfac\/wp-json\/wp\/v2\/media?parent=577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fac-seguridad.es\/blogfac\/wp-json\/wp\/v2\/categories?post=577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fac-seguridad.es\/blogfac\/wp-json\/wp\/v2\/tags?post=577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}